{"id":10799,"date":"2024-10-15T11:44:37","date_gmt":"2024-10-15T09:44:37","guid":{"rendered":"https:\/\/preprod.montefiore.eu\/?p=10799"},"modified":"2024-10-22T12:13:17","modified_gmt":"2024-10-22T10:13:17","slug":"montefiore-investment-acquisisce-la-maggioranza-di-ciela-village","status":"publish","type":"post","link":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/","title":{"rendered":"Montefiore Investment acquisisce da Vam Investments la quota di maggioranza in Demenego, storico marchio italiano nel settore dell\u2019occhialeria"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-2&#8243; icon_family=&#8221;none&#8221; text=&#8221;VERSIONE PDF&#8221; url=&#8221;\/wp-content\/uploads\/2024\/10\/Press-Release-Exit-Demenego_ITA.docx-1.pdf&#8221;][nectar_global_section id=&#8221;10691&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Vam Investments, investitore di private equity e partner dei principali family office italiani e internazionali, e Montefiore Investment, fondo di private equity pan-europeo dedicato alle piccole e medie imprese, annunciano di aver firmato un accordo vincolante per la cessione di Demenego, catena di centri ottici specializzati leader nel Nord-Est Italia. <\/strong><\/p>\n<p>Fondata nel 1960 dalla famiglia Demenego, la societ\u00e0 \u00e8 stata acquisita da Vam Investments nel 2020, con la contestuale nomina di Alessandro Donadelli a nuovo Amministratore Delegato.<br \/>\nGrazie alla lunga esperienza nel settore di Alessandro Donadelli e alla partnership con Vam Investments, la societ\u00e0 ha consolidato la presenza nell\u2019area del Triveneto ed ha cominciato a espandere la rete commerciale alle regioni confinanti, passando da 15 a 39 punti vendita previsti entro fine 2024. Parallelamente al processo di espansione geografica, il fatturato \u00e8 pi\u00f9 che raddoppiato, con una previsione di oltre 40 milioni di euro nel 2024.<br \/>\nCon la nuova partnership con Montefiore Investment, Demenego continuer\u00e0 a costruire il proprio successo su solide basi e un modello di business che concilia un\u2019offerta healthcare di alto livello con la vendita retail nei propri centri ottici. Tutti i negozi sono dotati di attrezzature mediche all&#8217;avanguardia per controllare, misurare e correggere la vista. La gamma di prodotti, che comprende occhiali da vista e da sole, sia a marchio privato che di terzi, \u00e8 pensata per rispondere a qualsiasi esigenza del cliente.<br \/>\nGrazie ai continui e significativi investimenti in digitalizzazione, personalizzazione, tecnologia e integrazione di tutti i processi in sistemi interconnessi tra loro, Demenego continuer\u00e0 a rivoluzionare l&#8217;esperienza d&#8217;acquisto con i suoi Demenego Labs, presenti in tutti i punti vendita, che consentono ai clienti di seguire le varie fasi di produzione dei loro occhiali, che vengono completati in appena un&#8217;ora.<br \/>\nMontefiore Investment, riconosciuta per la sua capacit\u00e0 di aiutare societ\u00e0 locali a diventare leader nazionali, porter\u00e0 competenze ed esperienza per sostenere e trasformare ulteriormente Demenego in uno specialista dell&#8217;occhialeria innovativo, omnicanale e in rapida crescita.<\/p>\n<blockquote><p><em>\u00ab Siamo orgogliosi di aver contribuito al percorso di crescita intrapreso in questi quattro anni da Demenego, un chiaro esempio della nostra strategia di investimento, basata sulla selezione attenta di aziende che eccellono nel loro segmento di mercato e che abbiano ancora un evidente potenziale da esprimere. Siamo grati ad Alessandro Donadelli e al suo team per aver guidato con successo l&#8217;azienda attraverso una transizione generazionale e per il loro straordinario lavoro nel creare valore per tutti gli stakeholder. Grazie ai loro sforzi, Demenego \u00e8 ben posizionata per continuare la sua traiettoria di sviluppo con Montefiore Investment, per raggiungere nuovi traguardi\u00bb<\/em><\/p>\n<p><strong>Marco Piana, Fondatore e Amministratore Delegato di Vam Investments<\/strong><\/p>\n<p><em>\u00ab Demenego \u00e8 un\u2019azienda ricca di competenze, innovazione ed attenzione maniacale al suo principio fondamentale \u201cvedere bene per vivere bene\u201d e sono state poste solide basi per i prossimi successi. Voglio ringraziare Vam Investments per il supporto e dare il benvenuto a Montefiore Investment. Con il nostro nuovo partner, che ci ha ribadito la sua fiducia confermando tutto il nostro team, abbiamo delineato un nuovo piano di crescita sfidante ed entusiasmante da realizzare per consentire a un numero sempre maggiore di persone di \u2018vedere bene per vivere bene \u00bb<\/em><\/p>\n<p><strong>Alessandro Donadelli, Amministratore Delegato di Demenego<\/strong><\/p>\n<p><em>Siamo entusiasti di collaborare con tutta la squadra guidata da Alessandro e non vediamo l&#8217;ora di contribuire all&#8217;incredibile percorso di crescita intrapreso da Demenego. Questo investimento segna uno step significativo nell&#8217;espansione di Montefiore nel mercato italiano e sottolinea il nostro costante impegno a sostenere aziende ambiziose nelle loro strategie di crescita. L&#8217;eccellente e distintivo store concept di Demenego, unito al know-how di Montefiore nel supportare le aziende del mid-market, creano la partnership perfetta per accrescere ulteriormente la presenza nel mercato italiano dell&#8217;occhialeria e continuare a sviluppare Demenego a un ritmo sostenuto\u00bb<\/em><\/p>\n<p><strong>Henri Topiol, Partner e Co-Head of Italy e Marie Londero, Executive Director di Montefiore Investment<\/strong><\/p><\/blockquote>\n[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b>Demenego<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Fondata nel 1960 a Calalzo di Cadore, Veneto,\u00a0Demenego\u00a0\u00e8 una delle principali catene italiane di centri ottici specializzati. Negli anni, l\u2019azienda ha rafforzato la propria presenza sul territorio e prevede di chiudere l\u2019anno con una rete di 39 negozi nel nord-est Italia, impiegando circa 270 risorse.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Parte integrante di ogni punto vendita \u00e8 la presenza di personale specializzato, che si prende cura del cliente dal momento dell\u2019esame della vista fino alla consegna dell\u2019occhiale, selezionabile, anche on line, tra un\u2019ampia gamma di oltre 4500 modelli a marchio\u00a0Demenego\u00a0o delle Major dell\u2019occhialeria. L\u2019azienda gode di un\u2019ottima reputazione, certificata dalla presenza di una clientela fedele e ricorrente che, ad oggi, conta circa 630 mila clienti registrati.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La societ\u00e0 prevede di chiudere l\u2019anno con un fatturato di circa 45 milioni di euro ed una redditivit\u00e0 ai vertici settoriali.<\/span><\/p>\n<p><a href=\"http:\/\/www.demenego.it\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">www.demenego.it<\/span><\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b>Vam Investments\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Vam Investments \u00e8 una societ\u00e0 di private equity specializzata in operazioni di buyout e aggregazioni strategiche, nata dall\u2019unione dell\u2019esperienza nel private markets di Marco Piana (CEO), e quella imprenditoriale e manageriale di Francesco Trapani (Executive Chairman), che consente di operare con flessibilit\u00e0 ed un approccio hands-on nei confronti delle societ\u00e0 in portafoglio. Vam Investments, che ha investito circa 400 milioni di euro negli ultimi 5 anni, affianca imprenditori e manager in aziende leader nei rispettivi settori per promuoverne lo sviluppo operativo, gestire la transizione generazionale e il processo di acquisizioni aggiuntive (add-on) per creare valore nel lungo periodo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vam opera con un modello di private equity deal-by-deal a cui partecipano family office di alto profilo italiani ed internazionali, oltre a investitori istituzionali. Lo stesso top management di Vam Investments partecipa attivamente a tutti gli investimenti.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Oggi Vam Investments ha partecipazioni, tra le altre, in Gruppo Florence, ConformGest, Slam, Sicurezza&amp;Ambiente e Supermoney.<\/span><\/p>\n<p><a href=\"http:\/\/www.vaminvestments.com\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">www.vaminvestments.com<\/span><\/a><span style=\"font-weight: 400;\">\u00a0<\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b>Montefiore Investment<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Nata nel 2005, Montefiore Investment \u00e8 la societ\u00e0 di Private Equity di riferimento dedicata al servizio delle PMI e delle aziende del mid-market. Con un team di 50 dipendenti e facendo leva sulla sua esperienza e sul suo know-how settoriale, Montefiore Investment supporta con successo le aziende nei loro progetti di crescita e sviluppo. Le attivit\u00e0 di Montefiore in Italia sono coordinate da Carlo Mammola (Presidente) ed Henri Topiol (Partner). La societ\u00e0 ha dimostrato la sua capacit\u00e0 di trasformare le PMI e le aziende a media capitalizzazione in veri campioni europei. I suoi risultati le hanno permesso di affermarsi come player chiave nel segmento mid-market del private equity. Con sede a Parigi e Milano, Montefiore Investment gestisce attualmente 5 miliardi di euro di capitale proprio e investe in ticket di dimensioni comprese tra 20 e 200 milioni di euro per finanziare una crescita sostenibile e redditizia delle societ\u00e0 in portafoglio. Dal 2021 Montefiore \u00e8 anche azionista e partner strategico di Starquest, una societ\u00e0 di gestione dedicata agli investimenti in aziende innovative a forte impatto ambientale (GreenTech).<\/span><\/p>\n<p><a href=\"http:\/\/www.montefiore.eu\"><span style=\"font-weight: 400;\">www.montefiore.eu<\/span><\/a><span style=\"font-weight: 400;\">\u00a0<\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b>Per ulteriori informazioni:<\/b><\/p>\n<p><b><i>Vam Investments<br \/>\n<\/i><\/b><b><i>Ufficio stampa<br \/>\n<\/i><\/b><span style=\"font-weight: 400;\">Image Building<br \/>\n<\/span><span style=\"font-weight: 400;\">Cristina Fossati, Luisella Murtas, Denise Recchiuto<br \/>\n<\/span><span style=\"font-weight: 400;\">+39 02 89011300<br \/>\n<\/span><a href=\"mailto:vaminvestments@imagebuilding.it\"><span style=\"font-weight: 400;\">vaminvestments@imagebuilding.it<\/span><\/a><\/p>\n<p><b><i>Montefiore Investment<br \/>\n<\/i><\/b><b><i>Ufficio stampa<br \/>\n<\/i><\/b><i><span style=\"font-weight: 400;\">Ad Hoc Communication Advisors<br \/>\n<\/span><\/i><span style=\"font-weight: 400;\">Valentina Zanotto\/Simona Di Nicola<br \/>\n<\/span><span style=\"font-weight: 400;\">+39 02 7606741<br \/>\n<\/span><a href=\"mailto:valentina.zanotto@ahca.it\"><span style=\"font-weight: 400;\">valentina.zanotto@ahca.it<\/span><\/a><span style=\"font-weight: 400;\">; <\/span><a href=\"mailto:simona.dinicola@ahca.it\"><span style=\"font-weight: 400;\">simona.dinicola@ahca.it<\/span><\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[186],"tags":[],"class_list":["post-10799","post","type-post","status-publish","format-standard","category-comunicato-stampa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Montefiore Investment acquisisce da Vam Investments la quota di maggioranza in Demenego, storico marchio italiano nel settore dell\u2019occhialeria - Montefiore Investment<\/title>\n<meta name=\"description\" content=\"Montefiore Investment, soci\u00e9t\u00e9 d\u2019investissement de r\u00e9f\u00e9rence des PME et ETI de services en Europe, annonce son investissement dans le groupe d\u2019h\u00f4tellerie de plein air Ciela Village, afin de consolider sa position sur le march\u00e9 fran\u00e7ais et de cr\u00e9er un acteur de premier plan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montefiore Investment acquisisce da Vam Investments la quota di maggioranza in Demenego, storico marchio italiano nel settore dell\u2019occhialeria - Montefiore Investment\" \/>\n<meta property=\"og:description\" content=\"Montefiore Investment, soci\u00e9t\u00e9 d\u2019investissement de r\u00e9f\u00e9rence des PME et ETI de services en Europe, annonce son investissement dans le groupe d\u2019h\u00f4tellerie de plein air Ciela Village, afin de consolider sa position sur le march\u00e9 fran\u00e7ais et de cr\u00e9er un acteur de premier plan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/\" \/>\n<meta property=\"og:site_name\" content=\"Montefiore Investment\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-15T09:44:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T10:13:17+00:00\" \/>\n<meta name=\"author\" content=\"WeAreBlow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"WeAreBlow\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\\\/\"},\"author\":{\"name\":\"WeAreBlow\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\"},\"headline\":\"Montefiore Investment acquisisce da Vam Investments la quota di maggioranza in Demenego, storico marchio italiano nel settore dell\u2019occhialeria\",\"datePublished\":\"2024-10-15T09:44:37+00:00\",\"dateModified\":\"2024-10-22T10:13:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\\\/\"},\"wordCount\":2124,\"articleSection\":[\"Comunicato stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\\\/\",\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\\\/\",\"name\":\"Montefiore Investment acquisisce da Vam Investments la quota di maggioranza in Demenego, storico marchio italiano nel settore dell\u2019occhialeria - Montefiore Investment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#website\"},\"datePublished\":\"2024-10-15T09:44:37+00:00\",\"dateModified\":\"2024-10-22T10:13:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\"},\"description\":\"Montefiore Investment, soci\u00e9t\u00e9 d\u2019investissement de r\u00e9f\u00e9rence des PME et ETI de services en Europe, annonce son investissement dans le groupe d\u2019h\u00f4tellerie de plein air Ciela Village, afin de consolider sa position sur le march\u00e9 fran\u00e7ais et de cr\u00e9er un acteur de premier plan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Montefiore Investment acquisisce da Vam Investments la quota di maggioranza in Demenego, storico marchio italiano nel settore dell\u2019occhialeria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/\",\"name\":\"Montefiore Investment\",\"description\":\"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\",\"name\":\"WeAreBlow\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"caption\":\"WeAreBlow\"},\"sameAs\":[\"https:\\\/\\\/montefiore.eu\"],\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/author\\\/weareblow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Montefiore Investment acquisisce da Vam Investments la quota di maggioranza in Demenego, storico marchio italiano nel settore dell\u2019occhialeria - Montefiore Investment","description":"Montefiore Investment, soci\u00e9t\u00e9 d\u2019investissement de r\u00e9f\u00e9rence des PME et ETI de services en Europe, annonce son investissement dans le groupe d\u2019h\u00f4tellerie de plein air Ciela Village, afin de consolider sa position sur le march\u00e9 fran\u00e7ais et de cr\u00e9er un acteur de premier plan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/","og_locale":"it_IT","og_type":"article","og_title":"Montefiore Investment acquisisce da Vam Investments la quota di maggioranza in Demenego, storico marchio italiano nel settore dell\u2019occhialeria - Montefiore Investment","og_description":"Montefiore Investment, soci\u00e9t\u00e9 d\u2019investissement de r\u00e9f\u00e9rence des PME et ETI de services en Europe, annonce son investissement dans le groupe d\u2019h\u00f4tellerie de plein air Ciela Village, afin de consolider sa position sur le march\u00e9 fran\u00e7ais et de cr\u00e9er un acteur de premier plan.","og_url":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/","og_site_name":"Montefiore Investment","article_published_time":"2024-10-15T09:44:37+00:00","article_modified_time":"2024-10-22T10:13:17+00:00","author":"WeAreBlow","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"WeAreBlow","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/#article","isPartOf":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/"},"author":{"name":"WeAreBlow","@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3"},"headline":"Montefiore Investment acquisisce da Vam Investments la quota di maggioranza in Demenego, storico marchio italiano nel settore dell\u2019occhialeria","datePublished":"2024-10-15T09:44:37+00:00","dateModified":"2024-10-22T10:13:17+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/"},"wordCount":2124,"articleSection":["Comunicato stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/","url":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/","name":"Montefiore Investment acquisisce da Vam Investments la quota di maggioranza in Demenego, storico marchio italiano nel settore dell\u2019occhialeria - Montefiore Investment","isPartOf":{"@id":"https:\/\/preprod.montefiore.eu\/it\/#website"},"datePublished":"2024-10-15T09:44:37+00:00","dateModified":"2024-10-22T10:13:17+00:00","author":{"@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3"},"description":"Montefiore Investment, soci\u00e9t\u00e9 d\u2019investissement de r\u00e9f\u00e9rence des PME et ETI de services en Europe, annonce son investissement dans le groupe d\u2019h\u00f4tellerie de plein air Ciela Village, afin de consolider sa position sur le march\u00e9 fran\u00e7ais et de cr\u00e9er un acteur de premier plan.","breadcrumb":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-da-vam-investments-la-quota-di-maggioranza-in-demenego-storico-marchio-italiano-nel-settore-dellocchialeria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/preprod.montefiore.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Montefiore Investment acquisisce da Vam Investments la quota di maggioranza in Demenego, storico marchio italiano nel settore dell\u2019occhialeria"}]},{"@type":"WebSite","@id":"https:\/\/preprod.montefiore.eu\/it\/#website","url":"https:\/\/preprod.montefiore.eu\/it\/","name":"Montefiore Investment","description":"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.montefiore.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3","name":"WeAreBlow","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","caption":"WeAreBlow"},"sameAs":["https:\/\/montefiore.eu"],"url":"https:\/\/preprod.montefiore.eu\/it\/author\/weareblow\/"}]}},"_links":{"self":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/comments?post=10799"}],"version-history":[{"count":7,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10799\/revisions"}],"predecessor-version":[{"id":10814,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10799\/revisions\/10814"}],"wp:attachment":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/media?parent=10799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/categories?post=10799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/tags?post=10799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}