{"id":10779,"date":"2023-09-13T14:59:59","date_gmt":"2023-09-13T12:59:59","guid":{"rendered":"https:\/\/preprod.montefiore.eu\/montefiore-investment-annonce-le-closing-intermediaire-de-deux-nouveaux-fonds-a-hauteur-de-14-milliard-deuros\/"},"modified":"2024-10-09T09:49:09","modified_gmt":"2024-10-09T07:49:09","slug":"montefiore-investment-annonce-le-closing-intermediaire-de-deux-nouveaux-fonds-a-hauteur-de-14-milliard-deuros","status":"publish","type":"post","link":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/","title":{"rendered":"Montefiore Investment annuncia il closing intermedio di due nuovi fondi per un totale di 1,4 miliardi di euro"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-2&#8243; icon_family=&#8221;none&#8221; text=&#8221;VERSIONE PDF&#8221; url=&#8221;\/wp-content\/uploads\/2024\/10\/CS-Montefiore-vMLSD.pdf&#8221;][nectar_global_section id=&#8221;10691&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<b>Parigi e Milano, <\/b><b>13 <\/b><b>settembre 2023<\/b><span style=\"font-weight: 400;\">. Montefiore Investment, societ\u00e0 di private equity specializzata negli investimenti in PMI attive nel settore dei servizi e della distribuzione, annuncia il closing intermedio dei suoi fondi, &#8220;Montefiore Investment VI&#8221; e &#8220;Montefiore Investment Expansion&#8221;, per un importo complessivo superiore a 1,4 miliardi di euro. Questi due fondi complementari rimarranno in linea con la strategia di Montefiore Investment, e potranno effettuare investimenti dai 20 ai 200 milioni di euro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In questi ultimi mesi:<br \/>\n<\/span><span style=\"font-weight: 400;\">&#8211; Montefiore Investment Expansion, il fondo Small Cap, ha gi\u00e0 raggiunto il suo hard cap di 450 milioni di euro;<br \/>\n<\/span><span style=\"font-weight: 400;\">&#8211; Montefiore Investment VI, il fondo Mid Cap, ha gi\u00e0 raccolto 1 miliardo di euro e ha come obiettivo un hard cap di 1,4 miliardi di euro nei prossimi mesi.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quest\u2019ottima performance, in un contesto di mercato difficile per la raccolta fondi, \u00e8 stata resa possibile grazie alla fiducia degli investitori storici di Montefiore Investment,\u00a0 i quali hanno reinvestito a pi\u00f9 del 100% &#8211; nonch\u00e9 all\u2019ingresso in societ\u00e0 di molti altri importanti investitori internazionali e francesi, in particolare istituzionali.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo closing intermedio giunge al termine di un primo semestre di particolare successo per Montefiore durante il quale:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sono stati effettuati quattro nuovi investimenti, permettendo di chiudere, in soli tre anni il periodo d\u2019investimento del fondo Montefiore Investment V e di realizzare il primo investimento di Montefiore Investment VI<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">E stata rinforzata la presenza internazionale con la realizzazione del primo investimento in Italia &#8211; grazie al nuovo team con sede a Milano . Negli scorsi mesi, la societ\u00e0 ha, infine, portato a\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sono state portate a termine tre cessioni, dimostrando ancora una volta la capacit\u00e0 del gruppo di creare valore nel tempo, nonostante il rallentamento del mercato.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Le societ\u00e0 nel portafoglio di Montefiore Investment hanno continuato il loro percorso di sviluppo, crescendo in modo significativo, con un aumento del fatturato e degli utili superiore al 20% su base annua, nonostante le incertezze macroeconomiche che stanno affrontando.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Con questi risultati, Montefiore Investment si afferma come uno degli investitori di maggior successo in Europa.<\/span><\/p>\n<p><b>Eric Bismuth, Presidente di Montefiore Investment, ha commentato<\/b><span style=\"font-weight: 400;\">: \u201c<em>Questi ottimi risultati sono il frutto della nostra ambiziosa strategia e delle elevate competenze dei nostri team a Parigi e Milano. Montefiore Investment continua a far crescere aziende di medie dimensioni con un elevato valore che contribuiscono a sostenere la crescita dell\u2019economia<\/em>\u201d.<\/span>[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Montefiore Investment<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Fondata nel 2005, Montefiore Investment \u00e8 l\u2019investitore di riferimento nelle PMI che operano nei settori dei servizi. Con un team di 50 professionisti e un\u2019esperienza e know-how settoriale, la societ\u00e0 supporta con successo le imprese nei loro progetti di crescita e sviluppo. Montefiore Investment ha dimostrato di poter trasformare le PMI in gruppi leader a livello europeo. Il suo track record l\u2019ha resa, inoltre, un punto di riferimento nel mid-market. Con sede a Parigi e a Milano, Montefiore Investment gestisce 4 miliardi di euro di asset under management, investendo tra i 20 e i 200 milioni di euro per operazione, per finanziare la crescita sostenibile e redditizia delle sue partecipazioni. Dal 2021, Montefiore \u00e8 inoltre azionista e partner strategico di Starquest, societ\u00e0 di gestione dedicata agli investimenti in aziende innovative ad alto impatto ambientale (GreenTech).<\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[186],"tags":[],"class_list":["post-10779","post","type-post","status-publish","format-standard","category-comunicato-stampa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Montefiore Investment annuncia il closing intermedio di due nuovi fondi per un totale di 1,4 miliardi di euro - Montefiore Investment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montefiore Investment annuncia il closing intermedio di due nuovi fondi per un totale di 1,4 miliardi di euro - Montefiore Investment\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/\" \/>\n<meta property=\"og:site_name\" content=\"Montefiore Investment\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-13T12:59:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-09T07:49:09+00:00\" \/>\n<meta name=\"author\" content=\"WeAreBlow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"WeAreBlow\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\\\/\"},\"author\":{\"name\":\"WeAreBlow\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\"},\"headline\":\"Montefiore Investment annuncia il closing intermedio di due nuovi fondi per un totale di 1,4 miliardi di euro\",\"datePublished\":\"2023-09-13T12:59:59+00:00\",\"dateModified\":\"2024-10-09T07:49:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\\\/\"},\"wordCount\":1009,\"articleSection\":[\"Comunicato stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\\\/\",\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\\\/\",\"name\":\"Montefiore Investment annuncia il closing intermedio di due nuovi fondi per un totale di 1,4 miliardi di euro - Montefiore Investment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#website\"},\"datePublished\":\"2023-09-13T12:59:59+00:00\",\"dateModified\":\"2024-10-09T07:49:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Montefiore Investment annuncia il closing intermedio di due nuovi fondi per un totale di 1,4 miliardi di euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/\",\"name\":\"Montefiore Investment\",\"description\":\"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\",\"name\":\"WeAreBlow\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"caption\":\"WeAreBlow\"},\"sameAs\":[\"https:\\\/\\\/montefiore.eu\"],\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/author\\\/weareblow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Montefiore Investment annuncia il closing intermedio di due nuovi fondi per un totale di 1,4 miliardi di euro - Montefiore Investment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/","og_locale":"it_IT","og_type":"article","og_title":"Montefiore Investment annuncia il closing intermedio di due nuovi fondi per un totale di 1,4 miliardi di euro - Montefiore Investment","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;...","og_url":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/","og_site_name":"Montefiore Investment","article_published_time":"2023-09-13T12:59:59+00:00","article_modified_time":"2024-10-09T07:49:09+00:00","author":"WeAreBlow","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"WeAreBlow","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/#article","isPartOf":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/"},"author":{"name":"WeAreBlow","@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3"},"headline":"Montefiore Investment annuncia il closing intermedio di due nuovi fondi per un totale di 1,4 miliardi di euro","datePublished":"2023-09-13T12:59:59+00:00","dateModified":"2024-10-09T07:49:09+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/"},"wordCount":1009,"articleSection":["Comunicato stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/","url":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/","name":"Montefiore Investment annuncia il closing intermedio di due nuovi fondi per un totale di 1,4 miliardi di euro - Montefiore Investment","isPartOf":{"@id":"https:\/\/preprod.montefiore.eu\/it\/#website"},"datePublished":"2023-09-13T12:59:59+00:00","dateModified":"2024-10-09T07:49:09+00:00","author":{"@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3"},"breadcrumb":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-il-closing-intermedio-di-due-nuovi-fondi-per-un-totale-di-14-miliardi-di-euro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/preprod.montefiore.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Montefiore Investment annuncia il closing intermedio di due nuovi fondi per un totale di 1,4 miliardi di euro"}]},{"@type":"WebSite","@id":"https:\/\/preprod.montefiore.eu\/it\/#website","url":"https:\/\/preprod.montefiore.eu\/it\/","name":"Montefiore Investment","description":"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.montefiore.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3","name":"WeAreBlow","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","caption":"WeAreBlow"},"sameAs":["https:\/\/montefiore.eu"],"url":"https:\/\/preprod.montefiore.eu\/it\/author\/weareblow\/"}]}},"_links":{"self":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/comments?post=10779"}],"version-history":[{"count":2,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10779\/revisions"}],"predecessor-version":[{"id":10781,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10779\/revisions\/10781"}],"wp:attachment":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/media?parent=10779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/categories?post=10779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/tags?post=10779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}