{"id":10774,"date":"2023-12-19T09:33:32","date_gmt":"2023-12-19T07:33:32","guid":{"rendered":"https:\/\/preprod.montefiore.eu\/?p=10774"},"modified":"2024-10-09T09:38:52","modified_gmt":"2024-10-09T07:38:52","slug":"montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group","status":"publish","type":"post","link":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/","title":{"rendered":"Montefiore Investment annuncia l\u2019ingresso di Latour Capital nel capitale di European Digital Group"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-2&#8243; icon_family=&#8221;none&#8221; text=&#8221;VERSIONE PDF&#8221; url=&#8221;\/wp-content\/uploads\/2024\/10\/CS-Montefiore-Investment-e-European-Digital-Group-entrano-in-trattativa-esclusiva-con-Latour-Capital-REV-18.12.pdf&#8221;][nectar_global_section id=&#8221;10691&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><strong>Milano, 19 dicembre 2023<\/strong>. Montefiore Investment, societa\u0300 di private equity specializzata negli investimenti in PMI attive nel settore dei servizi e della distribuzione, e European Digital Group (EDG) annunciano che Latour Capital ha acquisito una quota di EDG nell\u2019ambito di un\u2019operazione di LBO. Latour Capital e Montefiore Investment, azionista storico del Gruppo EDG, detengono congiuntamente la maggioranza del capitale di EDG, insieme a Vincent Klingbeil e al management<\/p>\n<p>Creata nel 2019 da Vincent Klingbeil ed Eric Bismuth, fondatore di Montefiore Investment, EDG e\u0300 diventata in soli 4 anni leader in Francia nell\u2019accelerazione digitale con quasi 1.700 dipendenti e un fatturato di oltre 250 milioni di euro. EDG e\u0300 in grado di supportare i propri clienti in tutti i settori digitali (CAC40, PMI, ecc.) grazie ad un\u2019offerta strutturata in 5 aree di competenza: Digital Content, Marketing Performance, Data &amp; AI, Cybersecurity &amp; Technology e Growth Enablers\/HR.<\/p>\n<p>L\u2019investimento da parte di Latour Capital e\u0300 volto ad accelerare lo sviluppo di EDG, sostenendone la crescita sia organica che attraverso acquisizioni, oltre che un\u2019ambiziosa strategia di espansione internazionale per portare il Gruppo a generare un fatturato di oltre 1 miliardo di euro in 5 anni. Questa operazione di LBO si inserisce in continuita\u0300 nel progetto di European Digital Group, che mantiene i propri azionisti storici come Montefiore Investment, il fondatore Vincent Klingbeil e l&#8217;intero management del gruppo.<\/p>\n<p>\u201c<em>E\u0300 per noi un grande orgoglio lavorare con EDG fin dalla sua nascita, affiancando un management team di grande competenza nello sviluppo del gruppo. Siamo quindi felici di accogliere Latour Capital in questa avventura imprenditoriale e di avviare una collaborazione con loro<\/em>\u201d, afferma <strong>Eric Bismuth, fondatore di Montefiore Investment<\/strong>.<\/p>\n<p>\u201c<em>Dopo aver ricevuto diverse offerte, abbiamo scelto Latour Capital, investitore francese con il quale condividiamo una visione comune e dei valori condivisi. E\u0300 con grande gioia che iniziamo questa nuova fase di sviluppo di EDG insieme a Latour Capital e al nostro partner di lunga data Montefiore Investment<\/em>\u201d, commenta <strong>Vincent Klingbeil, CEO e fondatore di European Digital Group<\/strong>.<\/p>\n<p>\u201c<em>Fin dall\u2019inizio siamo stati positivamente colpiti dalla qualita\u0300 del management team e dalla visione strategica di EDG, che lo rendono un gruppo leader in Francia nei suoi settori di riferimento. Siamo lieti di unirci a questa avventura insieme a Montefiore Investment e Vincent Klingbeil<\/em>\u201d, dichiara <strong>Philippe Leoni, Socio Fondatore di Latour Capital<\/strong>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Montefiore Investment <\/strong><\/p>\n<p>Fondata nel 2005, Montefiore Investment \u00e8 l\u2019investitore di riferimento nelle PMI che operano nei settori dei servizi. Con un team di 50 professionisti e un\u2019esperienza e know-how settoriale, la societ\u00e0 supporta con successo le imprese nei loro progetti di crescita e sviluppo. Montefiore Investment ha dimostrato di poter trasformare le PMI in gruppi leader a livello europeo. Il suo track record l\u2019ha resa, inoltre, un punto di riferimento nel mid-market. Con sede a Parigi e a Milano, Montefiore Investment gestisce 4 miliardi di euro di asset under management, investendo tra i 20 e i 200 milioni di euro per operazione, per finanziare la crescita sostenibile e redditizia delle sue partecipazioni. Dal 2021, Montefiore \u00e8 inoltre azionista e partner strategico di Starquest, societ\u00e0 di gestione dedicata agli investimenti in aziende innovative ad alto impatto ambientale (GreenTech).<\/p>\n<p>Per maggiori informazioni: <a href=\"https:\/\/preprod.montefiore.eu\/en\/\"><em>https:\/\/preprod.montefiore.eu\/en\/<\/em><\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Latour Capital<\/strong><\/p>\n<p>Latour Capital e\u0300 una societa\u0300 di gestione patrimoniale francese indipendente con una forte cultura imprenditoriale e una vasta esperienza sul campo. Con oltre 3 miliardi di euro in gestione e una ventina di professionisti, e\u0300 un investitore attivo che affianca il management delle societa\u0300 in portafoglio. Latour Capital investe principalmente in societa\u0300 con un forte potenziale di crescita in Francia e all&#8217;estero.<br \/>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>European Digital Group<\/strong><\/p>\n<p>European Digital Group e\u0300 il principale gruppo multispecialistico di accelerazione digitale per gli inserzionisti. Il gruppo conta oltre 1.700 professionisti e ha generato oltre 200 milioni di euro di ricavi nel 2022 con un target di 300 milioni di euro per il 2023. La sua mission e\u0300 quella di raccogliere in un&#8217;unica struttura persone specializzate in differenti aree connesse alla digitalizzazione, con l\u2019obiettivo di offrire ai propri clienti soluzioni personalizzate e accelerare la loro crescita. EDG ha sviluppato un&#8217;offerta all&#8217;avanguardia a supporto delle performance aziendali, che copre tutte le leve digitali e tecnologiche, attraverso 5 aree di competenza:<br \/>\n&#8211; <strong>Contenuti digitali:<\/strong> Follow (Referral &amp; Influence), Ore\u0300s (Strategia di branding e comunicazione), Kindai\u0308 (Creative Social Media), 140 Studio (Snack Content), Aura (Personal Branding), Andy (Celebrity Marketing), Original Band (Contenuti creativi), Produzione digitale (Contenuti digitali)<br \/>\n&#8211; <strong>Performance di marketing<\/strong>: Axome (e-commerce), Studio Zerance (esperti Shopify), Ad&#8217;s up Consulting e Caboost (Digital Performance), Clustaar by Ad&#8217;s up (SEO e dati), Optimize matter (Data &amp; Cloud Marketing)<br \/>\n&#8211; <strong>Dati e AI<\/strong>: Semantiweb &amp; Social Wire (Social Media Intelligence), Equancy (Dati e strategie AI), Dataventure (Data e Performance Marketing)<br \/>\n&#8211; <strong>Sicurezza informatica e tecnologia<\/strong>: Metsys (servizi IT e sicurezza informatica), Wold (innovazione digitale)<br \/>\n&#8211; <strong>Facilitatori di crescita<\/strong>: Avizio (HR Consulting Group), LesBigBoss (B2B Lead Generation), Proximum365 (Connessioni B2B mirate), Pitch Planet (Coaching commerciale), Campus by Ad&#8217;s up (Formazione sul marketing digitale).<\/p>\n<p>European Digital Group ha lanciato anche il Tech Show, lo spettacolo 100% online che mette in mostra i talenti della scena tecnologica e digitale! Per saperne di piu\u0300: <a href=\"http:\/\/www.europeandigital-group.com\" target=\"_blank\" rel=\"noopener\">www.europeandigital-group.com<\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[186],"tags":[],"class_list":["post-10774","post","type-post","status-publish","format-standard","category-comunicato-stampa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Montefiore Investment annuncia l\u2019ingresso di Latour Capital nel capitale di European Digital Group - Montefiore Investment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montefiore Investment annuncia l\u2019ingresso di Latour Capital nel capitale di European Digital Group - Montefiore Investment\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/\" \/>\n<meta property=\"og:site_name\" content=\"Montefiore Investment\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-19T07:33:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-09T07:38:52+00:00\" \/>\n<meta name=\"author\" content=\"WeAreBlow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"WeAreBlow\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\\\/\"},\"author\":{\"name\":\"WeAreBlow\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\"},\"headline\":\"Montefiore Investment annuncia l\u2019ingresso di Latour Capital nel capitale di European Digital Group\",\"datePublished\":\"2023-12-19T07:33:32+00:00\",\"dateModified\":\"2024-10-09T07:38:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\\\/\"},\"wordCount\":1664,\"articleSection\":[\"Comunicato stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\\\/\",\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\\\/\",\"name\":\"Montefiore Investment annuncia l\u2019ingresso di Latour Capital nel capitale di European Digital Group - Montefiore Investment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#website\"},\"datePublished\":\"2023-12-19T07:33:32+00:00\",\"dateModified\":\"2024-10-09T07:38:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Montefiore Investment annuncia l\u2019ingresso di Latour Capital nel capitale di European Digital Group\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/\",\"name\":\"Montefiore Investment\",\"description\":\"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\",\"name\":\"WeAreBlow\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"caption\":\"WeAreBlow\"},\"sameAs\":[\"https:\\\/\\\/montefiore.eu\"],\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/author\\\/weareblow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Montefiore Investment annuncia l\u2019ingresso di Latour Capital nel capitale di European Digital Group - Montefiore Investment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/","og_locale":"it_IT","og_type":"article","og_title":"Montefiore Investment annuncia l\u2019ingresso di Latour Capital nel capitale di European Digital Group - Montefiore Investment","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;...","og_url":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/","og_site_name":"Montefiore Investment","article_published_time":"2023-12-19T07:33:32+00:00","article_modified_time":"2024-10-09T07:38:52+00:00","author":"WeAreBlow","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"WeAreBlow","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/#article","isPartOf":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/"},"author":{"name":"WeAreBlow","@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3"},"headline":"Montefiore Investment annuncia l\u2019ingresso di Latour Capital nel capitale di European Digital Group","datePublished":"2023-12-19T07:33:32+00:00","dateModified":"2024-10-09T07:38:52+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/"},"wordCount":1664,"articleSection":["Comunicato stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/","url":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/","name":"Montefiore Investment annuncia l\u2019ingresso di Latour Capital nel capitale di European Digital Group - Montefiore Investment","isPartOf":{"@id":"https:\/\/preprod.montefiore.eu\/it\/#website"},"datePublished":"2023-12-19T07:33:32+00:00","dateModified":"2024-10-09T07:38:52+00:00","author":{"@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3"},"breadcrumb":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-annuncia-lingresso-di-latour-capital-nel-capitale-di-european-digital-group\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/preprod.montefiore.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Montefiore Investment annuncia l\u2019ingresso di Latour Capital nel capitale di European Digital Group"}]},{"@type":"WebSite","@id":"https:\/\/preprod.montefiore.eu\/it\/#website","url":"https:\/\/preprod.montefiore.eu\/it\/","name":"Montefiore Investment","description":"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.montefiore.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3","name":"WeAreBlow","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","caption":"WeAreBlow"},"sameAs":["https:\/\/montefiore.eu"],"url":"https:\/\/preprod.montefiore.eu\/it\/author\/weareblow\/"}]}},"_links":{"self":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/comments?post=10774"}],"version-history":[{"count":1,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10774\/revisions"}],"predecessor-version":[{"id":10775,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10774\/revisions\/10775"}],"wp:attachment":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/media?parent=10774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/categories?post=10774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/tags?post=10774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}