{"id":10687,"date":"2023-05-09T10:12:50","date_gmt":"2023-05-09T08:12:50","guid":{"rendered":"https:\/\/preprod.montefiore.eu\/?p=10687"},"modified":"2024-10-02T10:55:56","modified_gmt":"2024-10-02T08:55:56","slug":"montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa","status":"publish","type":"post","link":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/","title":{"rendered":"Montefiore Investment acquisisce la maggioranza del gruppo EXA"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-2&#8243; icon_family=&#8221;none&#8221; text=&#8221;VERSIONE PDF&#8221; url=&#8221;\/wp-content\/uploads\/2024\/10\/09052023_CS-Montefiore-Investment-acquisisce-la-maggioranza-di-EXA.pdf&#8221;][nectar_global_section id=&#8221;10691&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>Milano, 9 maggio 2023<\/strong>. Montefiore Investment, societ\u00e0 di private equity specializzata negli investimenti in PMI, annuncia l&#8217;acquisizione di una quota di maggioranza del gruppo italiano EXA, general contractor leader nei settori del lusso retail e dell\u2019hospitality. Montefiore Investment subentra al fondo Alcedo Sgr e si affianca ai fondatori che reinvestono nel Gruppo. Questa operazione \u00e8 la prima realizzata in Italia da Montefiore che, dallo scorso settembre, conta una sede a Milano in cui operano sette professionisti dedicati interamente al mercato locale.<\/p>\n<p>Fondata nel 2005, EXA si \u00e8 progressivamente affermata in Italia e a livello internazionale come leader nel project management per i marchi del lusso per tutti i loro progetti immobiliari: flagship store, hotel, uffici e showroom. Con circa 250 dipendenti, il Gruppo ha uffici in tre continenti e supporta pi\u00f9 di cento clienti in tutto il mondo, in particolare in Italia, Francia, Regno Unito e Stati Uniti.<\/p>\n<p>La partnership tra Montefiore e i fondatori di EXA mira ad attuare un ambizioso piano di crescita, in particolare al di fuori dell\u2019Italia, grazie ai valori che hanno guidato il successo del Gruppo nel proprio mercato domestico: impeccabile qualit\u00e0 di esecuzione, rispetto per le necessit\u00e0 dei clienti, know-how e sensibilit\u00e0 &#8220;made in Italy&#8221; e una capacit\u00e0 unica di realizzare prodotti su misura per adattarsi alle esigenze.<\/p>\n<p><strong>Giuseppe Polvani, Co-Fondatore e Amministratore Delegato di EXA<\/strong>, commenta: \u201c<em>Siamo grati ad Alcedo per il loro supporto in questi ultimi anni e non vediamo l&#8217;ora di iniziare questo nuovo capitolo insieme a Montefiore. Siamo stati colpiti dalla capacit\u00e0 del team di Montefiore di comprendere le nostre esigenze e proporre soluzioni concrete. Siamo certii che grazie a questa nuova collaborazione potremo ulteriormente accelerare la crescita del Gruppo<\/em>\u201d.<\/p>\n<p><strong>Henri Topiol, Partner di Montefiore Investment e Co-Head Ital<\/strong>y, aggiunge: \u201c<em>Siamo lieti di poter collaborare con i fondatori di EXA, gruppo nel quale abbiamo trovato professionisti di talento e focalizzati nel raggiungere obiettivi ambiziosi. Questa operazione rientra perfettamente nel DNA di Montefiore: competenza nel settore, spirito imprenditoriale, sviluppo internazionale e investimento nel capitale umano<\/em>\u201d.[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Montefiore Investment<\/p>\n<p>Fondata nel 2005, Montefiore Investment \u00e8 una societ\u00e0 di private equity specializzata negli investimenti in PMI che operano nel settore dei servizi. Grazie a un team di 50 dipendenti e all\u2019elevata esperienza e know-how settoriale, Montefiore supporta con successo le imprese nei loro progetti di crescita e sviluppo in Francia e in Italia, trasformandole in veri e propri leader europei. Il suo track record lo rende uno dei principali fondi francesi di private equity operativi nel mid-market. Con sede a Parigi e a Milano, Montefiore Investment gestisce oltre 4 miliardi di euro di asset, investendo tra 20 e 200 milioni di euro per ogni azienda. Dal 2021, Montefiore \u00e8 anche azionista e partner strategico di Starquest, societ\u00e0 di gestione dedicata agli investimenti in aziende innovative ad alto impatto ambientale (GreenTech).[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]EXA<\/p>\n<p>ExA nasce nel 2005 ad Arezzo, nel mondo del luxury retail. Oggi il Gruppo, con i suoi due marchi ExA e Mobil Project (creato nel 1987), copre oltre al luxury retail, molti altri settori del lusso tra cui hotel, uffici, showroom e residenze private.<br \/>\nIl Gruppo opera in ambienti internazionali complessi e ha aperto uffici vicini ai propri clienti a Milano, Parigi, Londra, New York, Doha e Dubai. Il Gruppo rispetta le esigenze di ciascun cliente, mantenendo un livello di qualit\u00e0 molto elevato.<br \/>\nGrazie ai suoi professionisti interni (ingegneri, architetti, industrial designer o project manager), il Gruppo offre ai suoi clienti un supporto a 360\u00b0 dalla fase di progettazione alla fine del cantiere, offrendo soluzioni ad alto valore aggiunto ed \u00e8 in grado di lavorare con metodi agili (Early-In Lean Contracting o IPD).<br \/>\nDalla sua creazione, il Gruppo ha completato oltre 1.200 progetti in tutto il mondo e pu\u00f2 contare su una rete di oltre 900 fornitori certificati.<\/p>\n<p><a href=\"https:\/\/exagroup.net\/\" target=\"_blank\" rel=\"noopener\">exagroup.net<\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[186],"tags":[],"class_list":["post-10687","post","type-post","status-publish","format-standard","category-comunicato-stampa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Montefiore Investment acquisisce la maggioranza del gruppo EXA - Montefiore Investment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montefiore Investment acquisisce la maggioranza del gruppo EXA - Montefiore Investment\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/\" \/>\n<meta property=\"og:site_name\" content=\"Montefiore Investment\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-09T08:12:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T08:55:56+00:00\" \/>\n<meta name=\"author\" content=\"WeAreBlow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"WeAreBlow\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\\\/\"},\"author\":{\"name\":\"WeAreBlow\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\"},\"headline\":\"Montefiore Investment acquisisce la maggioranza del gruppo EXA\",\"datePublished\":\"2023-05-09T08:12:50+00:00\",\"dateModified\":\"2024-10-02T08:55:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\\\/\"},\"wordCount\":1261,\"articleSection\":[\"Comunicato stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\\\/\",\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\\\/\",\"name\":\"Montefiore Investment acquisisce la maggioranza del gruppo EXA - Montefiore Investment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#website\"},\"datePublished\":\"2023-05-09T08:12:50+00:00\",\"dateModified\":\"2024-10-02T08:55:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Montefiore Investment acquisisce la maggioranza del gruppo EXA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/\",\"name\":\"Montefiore Investment\",\"description\":\"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/#\\\/schema\\\/person\\\/e3a5b12015dc28bd6274da38b94b43b3\",\"name\":\"WeAreBlow\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g\",\"caption\":\"WeAreBlow\"},\"sameAs\":[\"https:\\\/\\\/montefiore.eu\"],\"url\":\"https:\\\/\\\/preprod.montefiore.eu\\\/it\\\/author\\\/weareblow\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Montefiore Investment acquisisce la maggioranza del gruppo EXA - Montefiore Investment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/","og_locale":"it_IT","og_type":"article","og_title":"Montefiore Investment acquisisce la maggioranza del gruppo EXA - Montefiore Investment","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;...","og_url":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/","og_site_name":"Montefiore Investment","article_published_time":"2023-05-09T08:12:50+00:00","article_modified_time":"2024-10-02T08:55:56+00:00","author":"WeAreBlow","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"WeAreBlow","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/#article","isPartOf":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/"},"author":{"name":"WeAreBlow","@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3"},"headline":"Montefiore Investment acquisisce la maggioranza del gruppo EXA","datePublished":"2023-05-09T08:12:50+00:00","dateModified":"2024-10-02T08:55:56+00:00","mainEntityOfPage":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/"},"wordCount":1261,"articleSection":["Comunicato stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/","url":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/","name":"Montefiore Investment acquisisce la maggioranza del gruppo EXA - Montefiore Investment","isPartOf":{"@id":"https:\/\/preprod.montefiore.eu\/it\/#website"},"datePublished":"2023-05-09T08:12:50+00:00","dateModified":"2024-10-02T08:55:56+00:00","author":{"@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3"},"breadcrumb":{"@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/preprod.montefiore.eu\/it\/montefiore-investment-acquisisce-la-maggioranza-del-gruppo-exa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/preprod.montefiore.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Montefiore Investment acquisisce la maggioranza del gruppo EXA"}]},{"@type":"WebSite","@id":"https:\/\/preprod.montefiore.eu\/it\/#website","url":"https:\/\/preprod.montefiore.eu\/it\/","name":"Montefiore Investment","description":"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/preprod.montefiore.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/preprod.montefiore.eu\/it\/#\/schema\/person\/e3a5b12015dc28bd6274da38b94b43b3","name":"WeAreBlow","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4fe45c4c426fb5aa4064d00ab9add0ae2ca6ed3b17aeb23f05d9f8cd81f0f6c8?s=96&d=mm&r=g","caption":"WeAreBlow"},"sameAs":["https:\/\/montefiore.eu"],"url":"https:\/\/preprod.montefiore.eu\/it\/author\/weareblow\/"}]}},"_links":{"self":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/comments?post=10687"}],"version-history":[{"count":3,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10687\/revisions"}],"predecessor-version":[{"id":10695,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/posts\/10687\/revisions\/10695"}],"wp:attachment":[{"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/media?parent=10687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/categories?post=10687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.montefiore.eu\/it\/wp-json\/wp\/v2\/tags?post=10687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}